{"id":719,"date":"2026-05-04T18:45:26","date_gmt":"2026-05-04T18:45:26","guid":{"rendered":"https:\/\/archivohistorico.com.mx\/25\/?p=719"},"modified":"2026-05-06T16:44:51","modified_gmt":"2026-05-06T16:44:51","slug":"el-archivo-celebra-el-centenario-de-la-persecucion-contra-la-iglesia-en-mexico-con-cuatro-conferencias","status":"publish","type":"post","link":"https:\/\/archivohistorico.com.mx\/25\/index.php\/2026\/05\/04\/el-archivo-celebra-el-centenario-de-la-persecucion-contra-la-iglesia-en-mexico-con-cuatro-conferencias\/","title":{"rendered":"El Archivo celebra el centenario de la persecuci\u00f3n contra la Iglesia en M\u00e9xico con cuatro conferencias"},"content":{"rendered":"\n<p>El Archivo Hist\u00f3rico de la Arquidi\u00f3cesis de Chihuahua (AHACH) ha querido sumarse a las muchas celebraciones que se han estado&nbsp;haciendo&nbsp;en estos meses con ocasi\u00f3n del centenario del inicio de la Guerra Cristera y de la persecuci\u00f3n contra la Iglesia Cat\u00f3lica mexicana, durante las d\u00e9cadas de 1920 y 1930 del siglo XX.<\/p>\n\n\n\n<p>Un aspecto particular que tendr\u00e1 la celebraci\u00f3n promovida por el AHACH es que pondr\u00e1 una atenci\u00f3n especial a la persecuci\u00f3n contra la Iglesia en el estado de Chihuahua.<\/p>\n\n\n\n<p>La celebraci\u00f3n comprender\u00e1 cuatro conferencias que se llevar\u00e1n a cabo en la sede del AHACH los d\u00edas 20 y 26 de mayo y&nbsp;2 y 9 de junio de 2026, bajo el siguiente programa:<\/p>\n\n\n\n<p>Mayo:<\/p>\n\n\n\n<p>Mi\u00e9rcoles 20, 7:00 pm: La persecuci\u00f3n religiosa en la Rep\u00fablica Mexicana, su origen y desarrollo. Por el Ing. S. H\u00e9ctor Tarango.<\/p>\n\n\n\n<p>Martes 26, 7:00 pm: La persecuci\u00f3n religiosa en la di\u00f3cesis de Chihuahua. Por el P. Diz\u00e1n V\u00e1zquez.<\/p>\n\n\n\n<p>Junio:<\/p>\n\n\n\n<p>Martes 2, 7:00 pm: La Adoraci\u00f3n Nocturna Mexicana de Chihuahua en tiempos de la persecuci\u00f3n. Por el Antrop\u00f3logo Ricardo Schiebeck.<\/p>\n\n\n\n<p>Martes 9, 7,00 pm: Presentaci\u00f3n de la nueva edici\u00f3n de la vida del San Pedro Maldonado Lucero, del P. Diz\u00e1n V\u00e1zquez.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Archivo Hist\u00f3rico de la Arquidi\u00f3cesis de Chihuahua (AHACH) ha querido sumarse a las muchas celebraciones que se han estado&nbsp;haciendo&nbsp;en estos meses con ocasi\u00f3n del centenario del inicio de la Guerra Cristera y de la persecuci\u00f3n contra la Iglesia Cat\u00f3lica mexicana, durante las d\u00e9cadas de 1920 y 1930 del siglo XX. Un aspecto particular que tendr\u00e1 la celebraci\u00f3n promovida por el AHACH es que pondr\u00e1 una atenci\u00f3n especial a la persecuci\u00f3n contra la Iglesia en el estado de Chihuahua. La celebraci\u00f3n comprender\u00e1 cuatro conferencias que se llevar\u00e1n a cabo en la sede del AHACH los d\u00edas 20 y 26 de mayo y&nbsp;2 y 9 de junio de 2026, bajo el siguiente programa: Mayo: Mi\u00e9rcoles 20, 7:00 pm: La persecuci\u00f3n religiosa en la Rep\u00fablica Mexicana, su origen y desarrollo. Por el Ing. S. H\u00e9ctor Tarango. Martes 26, 7:00 pm: La persecuci\u00f3n religiosa en la di\u00f3cesis de Chihuahua. Por el P. Diz\u00e1n V\u00e1zquez. Junio: Martes 2, 7:00 pm: La Adoraci\u00f3n Nocturna Mexicana de Chihuahua en tiempos de la persecuci\u00f3n. Por el Antrop\u00f3logo Ricardo Schiebeck. Martes 9, 7,00 pm: Presentaci\u00f3n de la nueva edici\u00f3n de la vida del San Pedro Maldonado Lucero, del P. Diz\u00e1n V\u00e1zquez.<\/p>\n","protected":false},"author":1,"featured_media":720,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,27],"tags":[50],"class_list":["post-719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avisos","category-documentos","tag-archivo-historico-2"],"_links":{"self":[{"href":"https:\/\/archivohistorico.com.mx\/25\/index.php\/wp-json\/wp\/v2\/posts\/719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archivohistorico.com.mx\/25\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archivohistorico.com.mx\/25\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archivohistorico.com.mx\/25\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archivohistorico.com.mx\/25\/index.php\/wp-json\/wp\/v2\/comments?post=719"}],"version-history":[{"count":2,"href":"https:\/\/archivohistorico.com.mx\/25\/index.php\/wp-json\/wp\/v2\/posts\/719\/revisions"}],"predecessor-version":[{"id":731,"href":"https:\/\/archivohistorico.com.mx\/25\/index.php\/wp-json\/wp\/v2\/posts\/719\/revisions\/731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archivohistorico.com.mx\/25\/index.php\/wp-json\/wp\/v2\/media\/720"}],"wp:attachment":[{"href":"https:\/\/archivohistorico.com.mx\/25\/index.php\/wp-json\/wp\/v2\/media?parent=719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archivohistorico.com.mx\/25\/index.php\/wp-json\/wp\/v2\/categories?post=719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archivohistorico.com.mx\/25\/index.php\/wp-json\/wp\/v2\/tags?post=719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}